{"id":38,"date":"2023-10-24T08:00:00","date_gmt":"2023-10-24T08:00:00","guid":{"rendered":"https://www.h2xswimspa.com/blog/?p=38"},"modified":"2023-10-24T20:11:58","modified_gmt":"2023-10-24T20:11:58","slug":"swim-spa-deck-installation","status":"publish","type":"post","link":"https://www.h2xswimspa.com/blog/swim-spa-deck-installation/","title":{"rendered":"Swim spa installation on a deck: What you need to know"},"content":{"rendered":"\n<p>Con las ventajas de una piscina y un jacuzzi, los spas son la forma perfecta de mejorar su espacio exterior. Puede darse un baño relajante, aprovechar los chorros de masaje o simplemente estirarse en su flotador favorito. </p>\n\n\n\n<p>Pero al igual que los spas son una opción versátil para el ejercicio y la recreación en el agua, los propietarios de spas tienen una variedad de opciones de instalación. Puede instalar un spa de natación en una plataforma de hormigón, en una bóveda subterránea o, con la preparación adecuada, en una cubierta.</p>\n\n\n\n<p>Sí, ha leído bien: puede instalar un spa en una cubierta.</p>\n\n\n\n<p>Instalar un Swim Spa H2X Fitness de Master Spas en una cubierta puede ser una opción práctica a la vez que impresionante. La ubicación le permite tener acceso conveniente a la aptitud, a la reconstrucción, y a la relajación. Todo está a sólo unos pasos de las puertas de su patio. Además, puede resaltar el diseño de su nuevo oasis para todo el año.</p>\n\n\n\n<p>Sin embargo, hay algunas consideraciones que debe tener en cuenta al planificar la instalación de su swim spa. Los preparativos le ayudarán a disfrutar de los beneficios del ejercicio acuático y la relajación en la puerta de su casa.</p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https://h2xswimspa.es/h2x-swimspa-find-a-dealer\" target=\"_blank\" rel=\"noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"538\" src=\"https://h2xswimspa.es/blog/wp-content/uploads/2023/10/swim-spa-deck-installation-1024x538.jpg\" alt=\"swim spa deck\" class=\"wp-image-60\" srcset=\"https://h2xswimspa.es/blog/wp-content/uploads/2023/10/swim-spa-deck-installation-1024x538.jpg 1024w, https://h2xswimspa.es/blog/wp-content/uploads/2023/10/swim-spa-deck-installation-300x158.jpg 300w, https://h2xswimspa.es/blog/wp-content/uploads/2023/10/swim-spa-deck-installation-768x403.jpg 768w, https://h2xswimspa.es/blog/wp-content/uploads/2023/10/swim-spa-deck-installation-1536x807.jpg 1536w, https://h2xswimspa.es/blog/wp-content/uploads/2023/10/swim-spa-deck-installation-2048x1076.jpg 2048w, https://h2xswimspa.es/blog/wp-content/uploads/2023/10/swim-spa-deck-installation-520x273.jpg 520w, https://h2xswimspa.es/blog/wp-content/uploads/2023/10/swim-spa-deck-installation-740x389.jpg 740w, https://h2xswimspa.es/blog/wp-content/uploads/2023/10/swim-spa-deck-installation-150x79.jpg 150w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\"></a></figure>\n\n\n\n<h2 class=\"wp-block-heading\">¿Se puede poner un swim spa en una cubierta? </h2>\n\n\n\n<p>¿Se lo imagina? Sales por la puerta del patio y empiezas a nadar en cuestión de minutos. O tal vez se está remojando en los asientos de la bañera de hidromasaje mientras el sol se pone. La incorporación de un Swim Spa H2X Fitness en su terraza le permite disfrutar de su patio trasero de una manera nueva.</p>\n\n\n\n<p>Pero antes de retirar la cubierta y meterse en el agua, hay que preparar la cubierta para el spa.</p>\n\n\n\n<h3 class=\"wp-block-heading\">Evaluar la resistencia de la cubierta</h3>\n\n\n\n<p>Un spa de natación puede pesar hasta 24.000 libras cuando está lleno de agua y los miembros de la familia están nadando en el agua. Es crítico que no importa donde usted instala la alternativa de la piscina, que las fundaciones y apoyan el balneario.</p>\n\n\n\n<p>Si está pensando en colocar su spa en una cubierta existente, debe ponerse en contacto con un ingeniero estructural o un constructor de cubiertas profesional para evaluar la resistencia de su cubierta. Es posible que se necesiten refuerzos, como vigas de apoyo o zapatas adicionales.</p>\n\n\n\n<p>¿Está construyendo una cubierta nueva? Asegúrese de compartir las especificaciones del modelo de su spa con el contratista. Así podrá añadir cimientos más profundos o diseñar el espacio de forma inteligente para que usted pueda confiar en la resistencia de la cubierta.</p>\n\n\n\n<h3 class=\"wp-block-heading\">Plan de acceso y mantenimiento</h3>\n\n\n\n<p>Tendrá que asegurarse de que haya suficiente espacio alrededor del spa para el mantenimiento y las revisiones. Esto incluye el acceso al compartimento del equipo, que normalmente alberga bombas, filtros y calentadores. Master Spas recomienda que los propietarios tengan 3 pies de acceso en todos los lados en caso de que necesite servicio. Sin embargo, dependiendo del diseño de la cubierta de su spa, también puede considerar una sección desmontable de la cubierta o una trampilla para facilitar el acceso.</p>\n\n\n\n<p>Además, asegúrese de tener acceso a una manguera de jardín o a una llave de paso. Querrá poder <a href=\"https://youtu.be/o9I58DV3y_Y?si=2yxDofCzQA0dm8p1\" target=\"_blank\" rel=\"noreferrer noopener\">llenar el spa</a> de natación una vez que llegue. Además, los propietarios de spas de natación deberán añadir agua periódicamente, ya que las salpicaduras y la evaporación pueden reducir los niveles de agua.</p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https://h2xswimspa.es/h2x-swimspa-find-a-dealer\" target=\"_blank\" rel=\"noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"538\" src=\"https://h2xswimspa.es/blog/wp-content/uploads/2023/10/swim-dpa-deck-ideas-3-1024x538.jpg\" alt=\"swim spa ideas cubierta\" class=\"wp-image-56\" srcset=\"https://h2xswimspa.es/blog/wp-content/uploads/2023/10/swim-dpa-deck-ideas-3-1024x538.jpg 1024w, https://h2xswimspa.es/blog/wp-content/uploads/2023/10/swim-dpa-deck-ideas-3-300x158.jpg 300w, https://h2xswimspa.es/blog/wp-content/uploads/2023/10/swim-dpa-deck-ideas-3-768x403.jpg 768w, https://h2xswimspa.es/blog/wp-content/uploads/2023/10/swim-dpa-deck-ideas-3-1536x807.jpg 1536w, https://h2xswimspa.es/blog/wp-content/uploads/2023/10/swim-dpa-deck-ideas-3-2048x1076.jpg 2048w, https://h2xswimspa.es/blog/wp-content/uploads/2023/10/swim-dpa-deck-ideas-3-520x273.jpg 520w, https://h2xswimspa.es/blog/wp-content/uploads/2023/10/swim-dpa-deck-ideas-3-740x389.jpg 740w, https://h2xswimspa.es/blog/wp-content/uploads/2023/10/swim-dpa-deck-ideas-3-150x79.jpg 150w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\"></a></figure>\n\n\n\n<h3 class=\"wp-block-heading\">Facilidad de entrada y salida</h3>\n\n\n\n<p>Muchos spas vienen con un conjunto de escalones para entrar y salir del agua. Sin embargo, si instala el spa en una cubierta o junto a una estructura, es posible que no necesite escalones. Si el spa está nivelado con el suelo de la cubierta, bajarás al agua.</p>\n\n\n\n<p>Un diseño más funcional -y popular- es una configuración semiempotrada, en la que el spa se coloca ingeniosamente a una altura aproximada de 18 a 24 pulgadas por encima del suelo de la terraza. Este diseño no sólo realza el atractivo estético de su espacio exterior, sino que elimina la necesidad de escalones tradicionales. Podrá entrar y salir del agua sin esfuerzo. También puede colaborar con su contratista para construir una cubierta de varios niveles o diseñar escalones personalizados que combinen a la perfección con su decoración exterior, proporcionando una entrada acogedora a su swim spa. </p>\n\n\n\n<h3 class=\"wp-block-heading\">Preparar los cimientos</h3>\n\n\n\n<p>Independientemente de dónde instale su spa, es imprescindible contar con unos cimientos estables. En la mayoría de los casos, esto implica verter una plataforma de hormigón armado. También es importante que los cimientos estén nivelados y bien drenados.</p>\n\n\n\n<p>Aunque desee incorporar su spa de natación al diseño de la cubierta, es posible que la alternativa a la piscina no siempre se encuentre en la cubierta propiamente dicha. Muchas veces, el spa se instala sobre una plataforma de hormigón nivelada con el suelo y la cubierta se construye alrededor del spa. </p>\n\n\n\n<p>Si ya tienes una terraza, puedes contratar a un paisajista para que vierta una capa de hormigón y recorte la terraza para hacer sitio al spa. Otra alternativa es construir una plataforma específica para el spa. Piense en ella como una extensión de la terraza existente, situada convenientemente junto a ella para facilitar el acceso. Esta opción minimiza el impacto en el espacio de la cubierta actual.</p>\n\n\n\n<h3 class=\"wp-block-heading\">Consideraciones eléctricas</h3>\n\n\n\n<p>Un swim spa necesitará una conexión eléctrica. La mayoría de los spas H2X requieren un sistema de 50 amperios. Los modelos de spa de doble temperatura necesitarán un servicio de 100 amperios. Contrata a un electricista y fontanero con licencia para instalar el cableado necesario. Asegúrese de que estas conexiones cumplen los códigos de construcción y las normas de seguridad locales.</p>\n\n\n\n<p>Los modelos H2X Challenger requieren un disyuntor GFCI específico, que vendrá con su spa en el momento de la entrega. Es importante que se lo comunique claramente a su electricista. </p>\n\n\n\n<h3 class=\"wp-block-heading\">Entrega en balneario</h3>\n\n\n\n<p>Su distribuidor Master Spas trabajará con usted para coordinar la entrega de su spa. Asegúrese de que hay un camino despejado desde la calle hasta su terraza, ya que el spa puede ser bastante grande y pesado. </p>\n\n\n\n<p>Sin embargo, es importante compartir con el vendedor los planos de instalación del spa. Si tienes una terraza elevada o un acceso limitado al espacio, puede que necesites una grúa para levantar el spa y colocarlo en su sitio.</p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https://h2xswimspa.es/h2x-swimspa-find-a-dealer\" target=\"_blank\" rel=\"noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"538\" src=\"https://h2xswimspa.es/blog/wp-content/uploads/2023/10/swim-spa-deck-install-idea-1024x538.jpg\" alt=\"instalación de la cubierta del spa\" class=\"wp-image-59\" srcset=\"https://h2xswimspa.es/blog/wp-content/uploads/2023/10/swim-spa-deck-install-idea-1024x538.jpg 1024w, https://h2xswimspa.es/blog/wp-content/uploads/2023/10/swim-spa-deck-install-idea-300x158.jpg 300w, https://h2xswimspa.es/blog/wp-content/uploads/2023/10/swim-spa-deck-install-idea-768x403.jpg 768w, https://h2xswimspa.es/blog/wp-content/uploads/2023/10/swim-spa-deck-install-idea-1536x807.jpg 1536w, https://h2xswimspa.es/blog/wp-content/uploads/2023/10/swim-spa-deck-install-idea-2048x1076.jpg 2048w, https://h2xswimspa.es/blog/wp-content/uploads/2023/10/swim-spa-deck-install-idea-520x273.jpg 520w, https://h2xswimspa.es/blog/wp-content/uploads/2023/10/swim-spa-deck-install-idea-740x389.jpg 740w, https://h2xswimspa.es/blog/wp-content/uploads/2023/10/swim-spa-deck-install-idea-150x79.jpg 150w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\"></a></figure>\n\n\n\n<h2 class=\"wp-block-heading\">Cómo comprar un spa</h2>\n\n\n\n<p>¿Quiere poder nadar, hacer ejercicio y relajarse en casa? Disponer de un <a href=\"https://h2xswimspa.es/h2x-swimspa-find-a-dealer\">Swim Spa H2X Fitness de Master Spas</a> le permite nadar según sus horarios a la vez que añade un factor de diversión a su patio trasero. Puede <a href=\"https://h2xswimspa.es/health-benefits-of-a-swim-spa\">hacer clic aquí</a> para obtener más información sobre los beneficios de la hidroterapia y relajarse en un Swim Spa. O póngase en contacto con su distribuidor local de Master Spas para obtener más información sobre la propiedad de un swim spa. ¿Se pregunta cuánto cuesta un spa? Puede <a href=\"https://h2xswimspa.es/h2x-swimspa-find-a-dealer\">solicitar un presupuesto aquí</a>.</p>\n","protected":false},"excerpt":{"rendered":"<p>Al ofrecer las ventajas de una piscina y un jacuzzi, los spas son la forma perfecta de mejorar su espacio exterior. Podrá darse un baño relajante, aprovechar las <a class=\"read-more-link\" href=\"https://h2xswimspa.es/blog/swim-spa-deck-installation/\">Continue Reading</a></p>\n","protected":false},"author":3,"featured_media":61,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13],"tags":[],"class_list":["post-38","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-backyard-planning"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https://yoast.com/wordpress/plugins/seo/ -->\n<title>Instalación de Swim Spa en cubierta: Lo que hay que saber - H2X Blog</title>\n<meta name=\"description\" content=\"&quot;Maximice su espacio al aire libre: Instalar un spa en una terraza. Aprenda lo que necesita saber para una adición práctica y hermosa.\">\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\">\n<link rel=\"canonical\" href=\"https://h2xswimspa.es/blog/swim-spa-deck-installation/\">\n<meta property=\"og:locale\" content=\"en_US\">\n<meta property=\"og:type\" content=\"article\">\n<meta property=\"og:title\" content=\"Instalación de Swim Spa en cubierta: Lo que hay que saber - H2X Blog\">\n<meta property=\"og:description\" content=\"&quot;Maximice su espacio al aire libre: Instalar un spa en una terraza. Aprenda lo que necesita saber para una adición práctica y hermosa.\">\n<meta property=\"og:url\" content=\"https://h2xswimspa.es/blog/swim-spa-deck-installation/\">\n<meta property=\"og:site_name\" content=\"Blog de H2X Swim Spas\">\n<meta property=\"article:published_time\" content=\"2023-10-24T08:00:00+00:00\">\n<meta property=\"article:modified_time\" content=\"2023-10-24T20:11:58+00:00\">\n<meta property=\"og:image\" content=\"https://h2xswimspa.es/blog/wp-content/uploads/2023/10/swim-spa-deck-isntallation-fw.jpg\">\n\t<meta property=\"og:image:width\" content=\"2500\">\n\t<meta property=\"og:image:height\" content=\"1313\">\n\t<meta property=\"og:image:type\" content=\"image/jpeg\">\n<meta name=\"author\" content=\"Chris\">\n<meta name=\"twitter:card\" content=\"summary_large_image\">\n<meta name=\"twitter:label1\" content=\"Written by\">\n\t<meta name=\"twitter:data1\" content=\"Chris\">\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\">\n\t<meta name=\"twitter:data2\" content=\"6 minutes\">\n<script type=\"application/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https://schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https://h2xswimspa.es/blog/swim-spa-deck-installation/\",\"url\":\"https://h2xswimspa.es/blog/swim-spa-deck-installation/\",\"name\":\"Swim spa installation on a deck: What you need to know - H2X Blog\",\"isPartOf\":{\"@id\":\"https://h2xswimspa.es/blog/#website\"},\"primaryImageOfPage\":{\"@id\":\"https://h2xswimspa.es/blog/swim-spa-deck-installation/#primaryimage\"},\"image\":{\"@id\":\"https://h2xswimspa.es/blog/swim-spa-deck-installation/#primaryimage\"},\"thumbnailUrl\":\"https://h2xswimspa.es/blog/wp-content/uploads/2023/10/swim-spa-deck-isntallation-fw.jpg\",\"datePublished\":\"2023-10-24T08:00:00+00:00\",\"dateModified\":\"2023-10-24T20:11:58+00:00\",\"author\":{\"@id\":\"https://h2xswimspa.es/blog/#/schema/person/dc1771e0c9fb19465b7fe44f3ab49707\"},\"description\":\"\\\"Maximice su espacio al aire libre: Instalar un spa en una terraza. Aprenda lo que necesita saber para una adición práctica y hermosa.\",\"breadcrumb\":{\"@id\":\"https://h2xswimspa.es/blog/swim-spa-deck-installation/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https://h2xswimspa.es/blog/swim-spa-deck-installation/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https://h2xswimspa.es/blog/swim-spa-deck-installation/#primaryimage\",\"url\":\"https://h2xswimspa.es/blog/wp-content/uploads/2023/10/swim-spa-deck-isntallation-fw.jpg\",\"contentUrl\":\"https://h2xswimspa.es/blog/wp-content/uploads/2023/10/swim-spa-deck-isntallation-fw.jpg\",\"width\":2500,\"height\":1313,\"caption\":\"swim spa deck\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https://h2xswimspa.es/blog/swim-spa-deck-installation/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https://h2xswimspa.es/blog/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Swim spa installation on a deck: What you need to know\"}]},{\"@type\":\"WebSite\",\"@id\":\"https://h2xswimspa.es/blog/#website\",\"url\":\"https://h2xswimspa.es/blog/\",\"name\":\"H2X Swim Spas Blog\",\"description\":\"Consejos, trucos e inspiración para spas de natación\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https://h2xswimspa.es/blog/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https://h2xswimspa.es/blog/#/schema/person/dc1771e0c9fb19465b7fe44f3ab49707\",\"name\":\"Chris\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https://h2xswimspa.es/blog/#/schema/person/image/\",\"url\":\"https://secure.gravatar.com/avatar/a6673e0ebf2d20b095fba3eedab24827a79602f497cda2cc76d0e12fff76ceb7?s=96&d=mm&r=g\",\"contentUrl\":\"https://secure.gravatar.com/avatar/a6673e0ebf2d20b095fba3eedab24827a79602f497cda2cc76d0e12fff76ceb7?s=96&d=mm&r=g\",\"caption\":\"Chris\"},\"sameAs\":[\"http://Master%20Spas%20Staff\"]}]}</script>\n<!-- / Yoast SEO plugin. -->","yoast_head_json":{"title":"Swim spa installation on a deck: What you need to know - H2X Blog","description":"\"Maximice su espacio al aire libre: Instalar un spa en una terraza. Aprenda lo que necesita saber para una adición práctica y hermosa.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https://www.h2xswimspa.com/blog/swim-spa-deck-installation/","og_locale":"en_US","og_type":"article","og_title":"Swim spa installation on a deck: What you need to know - H2X Blog","og_description":"\"Maximize your outdoor space: Installing a swim spa on a deck. Learn what you need to know for a practical and beautiful addition.","og_url":"https://www.h2xswimspa.com/blog/swim-spa-deck-installation/","og_site_name":"H2X Swim Spas Blog","article_published_time":"2023-10-24T08:00:00+00:00","article_modified_time":"2023-10-24T20:11:58+00:00","og_image":[{"width":2500,"height":1313,"url":"https://h2xswimspa.es/blog/wp-content/uploads/2023/10/swim-spa-deck-isntallation-fw.jpg","type":"image/jpeg"}],"author":"Chris","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Chris","Est. reading time":"6 minutes"},"schema":{"@context":"https://schema.org","@graph":[{"@type":"WebPage","@id":"https://www.h2xswimspa.com/blog/swim-spa-deck-installation/","url":"https://h2xswimspa.es/blog/swim-spa-deck-installation/","name":"Swim spa installation on a deck: What you need to know - H2X Blog","isPartOf":{"@id":"https://www.h2xswimspa.com/blog/#website"},"primaryImageOfPage":{"@id":"https://www.h2xswimspa.com/blog/swim-spa-deck-installation/#primaryimage"},"image":{"@id":"https://www.h2xswimspa.com/blog/swim-spa-deck-installation/#primaryimage"},"thumbnailUrl":"https://www.h2xswimspa.com/blog/wp-content/uploads/2023/10/swim-spa-deck-isntallation-fw.jpg","datePublished":"2023-10-24T08:00:00+00:00","dateModified":"2023-10-24T20:11:58+00:00","author":{"@id":"https://www.h2xswimspa.com/blog/#/schema/person/dc1771e0c9fb19465b7fe44f3ab49707"},"description":"\"Maximice su espacio al aire libre: Instalar un spa en una terraza. Aprenda lo que necesita saber para una adición práctica y hermosa.","breadcrumb":{"@id":"https://www.h2xswimspa.com/blog/swim-spa-deck-installation/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https://www.h2xswimspa.com/blog/swim-spa-deck-installation/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https://www.h2xswimspa.com/blog/swim-spa-deck-installation/#primaryimage","url":"https://h2xswimspa.es/blog/wp-content/uploads/2023/10/swim-spa-deck-isntallation-fw.jpg","contentUrl":"https://www.h2xswimspa.com/blog/wp-content/uploads/2023/10/swim-spa-deck-isntallation-fw.jpg","width":2500,"height":1313,"caption":"swim spa deck"},{"@type":"BreadcrumbList","@id":"https://www.h2xswimspa.com/blog/swim-spa-deck-installation/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https://www.h2xswimspa.com/blog/"},{"@type":"ListItem","position":2,"name":"Swim spa installation on a deck: What you need to know"}]},{"@type":"WebSite","@id":"https://www.h2xswimspa.com/blog/#website","url":"https://h2xswimspa.es/blog/","name":"H2X Swim Spas Blog","description":"Consejos, trucos e inspiración para spas de natación","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https://www.h2xswimspa.com/blog/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https://www.h2xswimspa.com/blog/#/schema/person/dc1771e0c9fb19465b7fe44f3ab49707","name":"Chris","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https://www.h2xswimspa.com/blog/#/schema/person/image/","url":"https://secure.gravatar.com/avatar/a6673e0ebf2d20b095fba3eedab24827a79602f497cda2cc76d0e12fff76ceb7?s=96&d=mm&r=g","contentUrl":"https://secure.gravatar.com/avatar/a6673e0ebf2d20b095fba3eedab24827a79602f497cda2cc76d0e12fff76ceb7?s=96&d=mm&r=g","caption":"Chris"},"sameAs":["http://Master%20Spas%20Staff"]}]}},"_links":{"self":[{"href":"https://www.h2xswimspa.com/blog/wp-json/wp/v2/posts/38","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https://www.h2xswimspa.com/blog/wp-json/wp/v2/posts"}],"about":[{"href":"https://www.h2xswimspa.com/blog/wp-json/wp/v2/types/post"}],"author":[{"embeddable":true,"href":"https://www.h2xswimspa.com/blog/wp-json/wp/v2/users/3"}],"replies":[{"embeddable":true,"href":"https://www.h2xswimspa.com/blog/wp-json/wp/v2/comments?post=38"}],"version-history":[{"count":8,"href":"https://www.h2xswimspa.com/blog/wp-json/wp/v2/posts/38/revisions"}],"predecessor-version":[{"id":66,"href":"https://www.h2xswimspa.com/blog/wp-json/wp/v2/posts/38/revisions/66"}],"wp:featuredmedia":[{"embeddable":true,"href":"https://www.h2xswimspa.com/blog/wp-json/wp/v2/media/61"}],"wp:attachment":[{"href":"https://www.h2xswimspa.com/blog/wp-json/wp/v2/media?parent=38"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https://www.h2xswimspa.com/blog/wp-json/wp/v2/categories?post=38"},{"taxonomy":"post_tag","embeddable":true,"href":"https://www.h2xswimspa.com/blog/wp-json/wp/v2/tags?post=38"}],"curies":[{"name":"wp","href":"https://api.w.org/{rel}","templated":true}]}}