{"id":194,"date":"2023-12-19T08:00:18","date_gmt":"2023-12-19T08:00:18","guid":{"rendered":"https://www.h2xswimspa.com/blog/?p=194"},"modified":"2024-07-24T15:13:09","modified_gmt":"2024-07-24T15:13:09","slug":"ben-kanute-training","status":"publish","type":"post","link":"https://www.h2xswimspa.com/blog/ben-kanute-training/","title":{"rendered":"Catching up with pro triathlete Ben Kanute"},"content":{"rendered":"\n<p>El triatleta profesional Ben Kanute va a la piscina la mayoría de los días, nadando miles de metros por sesión mientras se prepara para carreras como el IRONMAN 70.3 Indian Wells y el PTO US Open.</p>\n\n\n\n<p>Para él, la piscina es un lugar para trabajar, no para pasar el rato.</p>\n\n\n\n<p>\"Nunca quise tener una piscina en el jardín\", dice este residente de Phoenix. Resulta casi difícil de creer, ya que la zona de Phoenix es conocida por su paisaje desértico y sus piscinas residenciales. Casi 1 de cada 3 casas tiene piscina, lo que no es de extrañar, ya que Arizona es uno de los estados más calurosos y sin salida al mar de Estados Unidos.</p>\n\n\n\n<p>Las piscinas residenciales de Arizona están diseñadas principalmente para relajarse, celebrar fiestas en la piscina y escapar del brutal calor. No responden a las necesidades específicas de un triatleta profesional como Kanute, cuyo entrenamiento exige una configuración más especializada.</p>\n\n\n\n<p>Una alternativa a la piscina, un H2X Fitness Swim Spa de Master Spas permite a Kanute realizar una sesión de natación de calidad a la vez que concilia la vida familiar. A diferencia de las piscinas tradicionales, este spa de natación ofrece una corriente de natación sin fin, proporcionando resistencia para una variedad de sesiones de entrenamiento, ya sea un largo nado de resistencia o una sesión de recuperación por la tarde.</p>\n\n\n\n<p>Cuando termine su sesión, su familia podrá unirse a él en el spa de natación para disfrutar de la diversión familiar que ofrece una piscina.</p>\n\n\n\n<p>Master Spas se reunió recientemente con Kanute para conocer cómo incorpora un spa de natación a su entrenamiento y los beneficios de una piscina de natación. </p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"538\" src=\"https://h2xswimspa.es/blog/wp-content/uploads/2024/06/kanute-swimming-1024x538.jpg\" alt=\"a qué velocidad se puede nadar en un spa\" class=\"wp-image-308\" srcset=\"https://h2xswimspa.es/blog/wp-content/uploads/2024/06/kanute-swimming-1024x538.jpg 1024w, https://h2xswimspa.es/blog/wp-content/uploads/2024/06/kanute-swimming-300x158.jpg 300w, https://h2xswimspa.es/blog/wp-content/uploads/2024/06/kanute-swimming-768x403.jpg 768w, https://h2xswimspa.es/blog/wp-content/uploads/2024/06/kanute-swimming-520x273.jpg 520w, https://h2xswimspa.es/blog/wp-content/uploads/2024/06/kanute-swimming-740x389.jpg 740w, https://h2xswimspa.es/blog/wp-content/uploads/2024/06/kanute-swimming-150x79.jpg 150w, https://h2xswimspa.es/blog/wp-content/uploads/2024/06/kanute-swimming.jpg 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\"></figure>\n\n\n\n<h2 class=\"wp-block-heading\">7 preguntas al triatleta profesional Ben Kanute</h2>\n\n\n\n<p>Ben Kanute se inició en el triatlón de niño, mientras crecía en la zona de Chicago. Ver a su padre practicar este deporte no hizo sino avivar su pasión y su afición.  </p>\n\n\n\n<p>En su transición al ámbito profesional, Ben no tardó en ascender, proclamándose varias veces campeón nacional de Estados Unidos y participando en los Juegos Olímpicos de Río 2016. También quedó segundo en los Campeonatos del Mundo IRONMAN 70.3 y se ha asegurado una plaza en los Campeonatos del Mundo IRONMAN de 2024 en Kailua-Kona.</p>\n\n\n\n<p>Kanute, que vive en la zona de Phoenix con su mujer y sus dos hijos, se entrena en un spa H2X Challenger 18D Pro. </p>\n\n\n\n<h3 class=\"wp-block-heading\">¿Cómo incorporas un spa de natación a tu entrenamiento de triatlón?</h3>\n\n\n\n<p>\"Lo utilizo sobre todo para nataciones fáciles o de resistencia. Así que entre el 30 y el 50 por ciento de mis nados semanales\", explica Kanute, que puede registrar hasta 30 o 35 horas de natación, ciclismo y carrera durante los picos de entrenamiento. </p>\n\n\n\n<h3 class=\"wp-block-heading\">¿Cómo mejora un swim spa la comodidad de los deportistas?</h3>\n\n\n\n<p>\"Tener el H2X Challenger 18D Pro me ha ahorrado mucho tiempo. Puedo nadar sin tener que desplazarme hasta la piscina\", afirma Kanute. </p>\n\n\n\n<p>Y añade: \"Si voy a nadar 30 ó 40 minutos en la piscina, probablemente tenga que conducir casi el equivalente para llegar a una de las piscinas de aquí. Así que es muy cómodo poder nadar en el jardín de mi casa. Y eso sólo para entrenar\".</p>\n\n\n\n<h3 class=\"wp-block-heading\">¿Cómo pueden mejorar su natación los triatletas?</h3>\n\n\n\n<p>\"Una de las mejores inversiones que puedes hacer en tu natación es que alguien te grabe en vídeo\", dice Kanute. \"No sólo podrás ver tu aspecto al nadar, que puede ser muy diferente de lo que sientes, sino que también podrás hacer ejercicios específicos para ti. Eso es importante porque todo el mundo tiene problemas ligeramente diferentes con su brazada de natación.\" </p>\n\n\n\n<p>Pero llevar una cámara subacuática a la piscina no siempre resulta práctico. Puede que te sientas cohibido o que las calles abarrotadas dificulten la obtención de un buen vídeo. </p>\n\n\n\n<p>Fijando una cámara acuática al lateral del spa o haciendo que un amigo la sostenga bajo el agua, puedes grabar tus brazadas, patadas y forma general. Además, puedes tomar varios ángulos de tu brazada para ver tu agarre, tirón y posición de la cadera, entre otros aspectos de tu forma.</p>\n\n\n\n<p>Puedes entregar los archivos de vídeo a tu entrenador o enviarlos a una plataforma que analice la forma de nadar. </p>\n\n\n\n<h3 class=\"wp-block-heading\">¿Cuáles son las claves para ser un nadador más rápido en triatlón?</h3>\n\n\n\n<p>\"No se puede forzar para ser un nadador más rápido. Se basa mucho más en la técnica que la carrera y el ciclismo, que siguen basándose en la técnica\", afirma Kanute. \"Pero lo es aún más porque te mueves a través de algo que es cinco o diez veces más espeso que el aire\". </p>\n\n\n\n<p>Kanute creció nadando y fue miembro de un equipo juvenil de triatlón. Al participar en esos programas, dedicaba mucho tiempo a los ejercicios.</p>\n\n\n\n<p>Los ejercicios de natación pueden ayudar a los triatletas a desarrollar y reforzar una buena posición corporal, crear memoria muscular y enseñar a su cuerpo una buena forma, además de mejorar su sensación en el agua. </p>\n\n\n\n<p>\"Cuando hago ejercicios, suelo centrarme en ejercicios como el nado con un brazo y la recuperación: los básicos afectan a la posición de mi cuerpo en el agua\", dice Kanute. </p>\n\n\n\n<p>\"Creo que los ejercicios con un brazo siempre son buenos para aislar cada lado y centrarse realmente en el tirón\".</p>\n\n\n\n<h3 class=\"wp-block-heading\">Los spas ofrecen una experiencia de natación continua. ¿En qué puede beneficiar esto a los triatletas?</h3>\n\n\n\n<p>\"En un spa de natación se nada directamente. Es algo único, porque no se tiene esa experiencia a menos que se vaya a aguas abiertas. Lo más cerca que un atleta puede estar de eso es nadar en una piscina de 50 metros\".</p>\n\n\n\n<p>Kanute añade: \"Incluso pasar de 25 metros a 50 es diferente, pero sigues haciendo giros y empujando desde la pared. Esos giros son siempre un reset\".</p>\n\n\n\n<p>Sin embargo, cuando nadas de forma continua, tienes que aprender a reajustarte sin la ayuda de una pared, igual que harías si te encontraras en un momento difícil en una carrera. Puedes centrarte en un aspecto concreto de tu brazada o en tu respiración. También puedes contar las brazadas. </p>\n\n\n\n<h3 class=\"wp-block-heading\">¿Cuál es su conjunto de baño favorito?</h3>\n\n\n\n<p>\"Si sólo tengo que nadar 3.000 metros, mi rutina es nadar 1.000 metros, tirar 1.000 metros, tirar 500 metros sin las palas y luego nadar 500 metros.  Y eso es sólo mentalmente para superarlo\". </p>\n\n\n\n<p>Y añade: \"Pero siempre me han gustado las series de prueba, cuando hago un entrenamiento en el que puedes ir cogiendo el ritmo. Los 10 ó 20 intervalos de 100 metros o los 10 de 200 metros. Son el tipo de entrenamientos en los que puedes nadar a ritmo de carrera con un intervalo relativamente corto\". </p>\n\n\n\n<p>¿Preferirías nadar un super sprint o un triatlón de larga distancia? </p>\n\n\n\n<p>\"Súper sprint, probablemente. Con 3,2 km, nadar un IRONMAN completo es bastante largo\", admite Kanute. \"Me gusta mucho la distancia IRONMAN, pero la natación puede parecerme muy larga\".</p>\n\n\n\n<h3 class=\"wp-block-heading\">¿Cuáles son sus objetivos para 2024?</h3>\n\n\n\n<p>El Campeonato del Mundo IRONMAN de Kona será mi carrera \"A\" del año\", dice Kanute. \"Tengo muchas ganas de correr en la isla: hay algo de magia detrás. Y poder correr un mundial en Estados Unidos siempre es divertido\".</p>\n\n\n\n<p>Kanute dice que la última vez que un estadounidense ganó en Kona fue en 2001, \"y mi padre estaba en la isla compitiendo ese año\".</p>\n\n\n\n<p>\"Y por eso lo traigo de vuelta. Así que espero que podamos conseguir que otro hombre estadounidense gane los Campeonatos del Mundo IRONMAN\".   </p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"538\" src=\"https://h2xswimspa.es/blog/wp-content/uploads/2024/05/swim-spa-rules-kanute-1024x538.jpg\" alt=\"normas del balneario\" class=\"wp-image-302\" srcset=\"https://h2xswimspa.es/blog/wp-content/uploads/2024/05/swim-spa-rules-kanute-1024x538.jpg 1024w, https://h2xswimspa.es/blog/wp-content/uploads/2024/05/swim-spa-rules-kanute-300x158.jpg 300w, https://h2xswimspa.es/blog/wp-content/uploads/2024/05/swim-spa-rules-kanute-768x403.jpg 768w, https://h2xswimspa.es/blog/wp-content/uploads/2024/05/swim-spa-rules-kanute-520x273.jpg 520w, https://h2xswimspa.es/blog/wp-content/uploads/2024/05/swim-spa-rules-kanute-740x389.jpg 740w, https://h2xswimspa.es/blog/wp-content/uploads/2024/05/swim-spa-rules-kanute-150x79.jpg 150w, https://h2xswimspa.es/blog/wp-content/uploads/2024/05/swim-spa-rules-kanute.jpg 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\"></figure>\n\n\n\n<h2 class=\"wp-block-heading\">¿Cómo comprar un spa?</h2>\n\n\n\n<p>¿Quiere poder nadar, hacer ejercicio y relajarse en casa? Disponer de un <a href=\"https://h2xswimspa.es/h2x-swimspa-find-a-dealer\">Swim Spa H2X Fitness de Master Spas</a> le permite nadar según sus horarios a la vez que añade un factor de diversión a su patio trasero. Puede <a href=\"https://h2xswimspa.es/health-benefits-of-a-swim-spa\">hacer clic aquí</a> para obtener más información sobre los beneficios de la hidroterapia y relajarse en un Swim Spa. O póngase en contacto con su distribuidor local de Master Spas para obtener más información sobre la propiedad de un swim spa. ¿Se pregunta cuánto cuesta un spa? Puede <a href=\"https://h2xswimspa.es/h2x-swimspa-find-a-dealer\">solicitar un presupuesto aquí</a>.</p>\n","protected":false},"excerpt":{"rendered":"<p>El triatleta profesional Ben Kanute va a la piscina la mayoría de los días, nadando miles de metros por sesión mientras se prepara para carreras como el IRONMAN 70.3 Indian Wells y el PTO US Open. Para él, la piscina <a class=\"read-more-link\" href=\"https://h2xswimspa.es/blog/ben-kanute-training/\">Continue Reading</a></p>\n","protected":false},"author":3,"featured_media":346,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11],"tags":[],"class_list":["post-194","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fitness"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.1.1 - https://yoast.com/wordpress/plugins/seo/ -->\n<title>Encuentro con el triatleta profesional Ben Kanute - H2X Blog</title>\n<meta name=\"description\" content=\"Descubre cómo Ben Kanute concilia la vida familiar y el entrenamiento en Arizona, utilizando un spa de natación para optimizar la comodidad y mejorar el rendimiento.\">\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\">\n<link rel=\"canonical\" href=\"https://h2xswimspa.es/blog/ben-kanute-training/\">\n<meta property=\"og:locale\" content=\"en_US\">\n<meta property=\"og:type\" content=\"article\">\n<meta property=\"og:title\" content=\"Encuentro con el triatleta profesional Ben Kanute - H2X Blog\">\n<meta property=\"og:description\" content=\"Descubre cómo Ben Kanute concilia la vida familiar y el entrenamiento en Arizona, utilizando un spa de natación para optimizar la comodidad y mejorar el rendimiento.\">\n<meta property=\"og:url\" content=\"https://h2xswimspa.es/blog/ben-kanute-training/\">\n<meta property=\"og:site_name\" content=\"Blog de H2X Swim Spas\">\n<meta property=\"article:published_time\" content=\"2023-12-19T08:00:18+00:00\">\n<meta property=\"article:modified_time\" content=\"2024-07-24T15:13:09+00:00\">\n<meta property=\"og:image\" content=\"https://h2xswimspa.es/blog/wp-content/uploads/2023/12/ben-kanute-hero.jpg\">\n\t<meta property=\"og:image:width\" content=\"1200\">\n\t<meta property=\"og:image:height\" content=\"630\">\n\t<meta property=\"og:image:type\" content=\"image/jpeg\">\n<meta name=\"author\" content=\"Chris\">\n<meta name=\"twitter:card\" content=\"summary_large_image\">\n<meta name=\"twitter:label1\" content=\"Written by\">\n\t<meta name=\"twitter:data1\" content=\"Chris\">\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\">\n\t<meta name=\"twitter:data2\" content=\"7 minutes\">\n<script type=\"application/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https://schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https://h2xswimspa.es/blog/ben-kanute-training/\",\"url\":\"https://h2xswimspa.es/blog/ben-kanute-training/\",\"name\":\"Catching up with pro triathlete Ben Kanute - H2X Blog\",\"isPartOf\":{\"@id\":\"https://h2xswimspa.es/blog/#website\"},\"primaryImageOfPage\":{\"@id\":\"https://h2xswimspa.es/blog/ben-kanute-training/#primaryimage\"},\"image\":{\"@id\":\"https://h2xswimspa.es/blog/ben-kanute-training/#primaryimage\"},\"thumbnailUrl\":\"https://h2xswimspa.es/blog/wp-content/uploads/2023/12/ben-kanute-hero.jpg\",\"datePublished\":\"2023-12-19T08:00:18+00:00\",\"dateModified\":\"2024-07-24T15:13:09+00:00\",\"author\":{\"@id\":\"https://h2xswimspa.es/blog/#/schema/person/dc1771e0c9fb19465b7fe44f3ab49707\"},\"description\":\"Descubre cómo Ben Kanute concilia la vida familiar y el entrenamiento en Arizona, utilizando un spa de natación para optimizar la comodidad y mejorar el rendimiento.\",\"breadcrumb\":{\"@id\":\"https://h2xswimspa.es/blog/ben-kanute-training/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https://h2xswimspa.es/blog/ben-kanute-training/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https://h2xswimspa.es/blog/ben-kanute-training/#primaryimage\",\"url\":\"https://h2xswimspa.es/blog/wp-content/uploads/2023/12/ben-kanute-hero.jpg\",\"contentUrl\":\"https://h2xswimspa.es/blog/wp-content/uploads/2023/12/ben-kanute-hero.jpg\",\"width\":1200,\"height\":630,\"caption\":\"triathlete ben kanute\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https://h2xswimspa.es/blog/ben-kanute-training/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https://h2xswimspa.es/blog/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Catching up with pro triathlete Ben Kanute\"}]},{\"@type\":\"WebSite\",\"@id\":\"https://h2xswimspa.es/blog/#website\",\"url\":\"https://h2xswimspa.es/blog/\",\"name\":\"H2X Swim Spas Blog\",\"description\":\"Consejos, trucos e inspiración para spas de natación\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https://h2xswimspa.es/blog/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https://h2xswimspa.es/blog/#/schema/person/dc1771e0c9fb19465b7fe44f3ab49707\",\"name\":\"Chris\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https://h2xswimspa.es/blog/#/schema/person/image/\",\"url\":\"https://secure.gravatar.com/avatar/a6673e0ebf2d20b095fba3eedab24827a79602f497cda2cc76d0e12fff76ceb7?s=96&d=mm&r=g\",\"contentUrl\":\"https://secure.gravatar.com/avatar/a6673e0ebf2d20b095fba3eedab24827a79602f497cda2cc76d0e12fff76ceb7?s=96&d=mm&r=g\",\"caption\":\"Chris\"},\"sameAs\":[\"http://Master%20Spas%20Staff\"]}]}</script>\n<!-- / Yoast SEO plugin. -->","yoast_head_json":{"title":"Catching up with pro triathlete Ben Kanute - H2X Blog","description":"Descubre cómo Ben Kanute concilia la vida familiar y el entrenamiento en Arizona, utilizando un spa de natación para optimizar la comodidad y mejorar el rendimiento.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https://www.h2xswimspa.com/blog/ben-kanute-training/","og_locale":"en_US","og_type":"article","og_title":"Catching up with pro triathlete Ben Kanute - H2X Blog","og_description":"Discover how Ben Kanute balances family life and training in Arizona, using a swim spa to optimize convenience and enhance performance","og_url":"https://www.h2xswimspa.com/blog/ben-kanute-training/","og_site_name":"H2X Swim Spas Blog","article_published_time":"2023-12-19T08:00:18+00:00","article_modified_time":"2024-07-24T15:13:09+00:00","og_image":[{"width":1200,"height":630,"url":"https://h2xswimspa.es/blog/wp-content/uploads/2023/12/ben-kanute-hero.jpg","type":"image/jpeg"}],"author":"Chris","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Chris","Est. reading time":"7 minutes"},"schema":{"@context":"https://schema.org","@graph":[{"@type":"WebPage","@id":"https://www.h2xswimspa.com/blog/ben-kanute-training/","url":"https://h2xswimspa.es/blog/ben-kanute-training/","name":"Catching up with pro triathlete Ben Kanute - H2X Blog","isPartOf":{"@id":"https://www.h2xswimspa.com/blog/#website"},"primaryImageOfPage":{"@id":"https://www.h2xswimspa.com/blog/ben-kanute-training/#primaryimage"},"image":{"@id":"https://www.h2xswimspa.com/blog/ben-kanute-training/#primaryimage"},"thumbnailUrl":"https://www.h2xswimspa.com/blog/wp-content/uploads/2023/12/ben-kanute-hero.jpg","datePublished":"2023-12-19T08:00:18+00:00","dateModified":"2024-07-24T15:13:09+00:00","author":{"@id":"https://www.h2xswimspa.com/blog/#/schema/person/dc1771e0c9fb19465b7fe44f3ab49707"},"description":"Descubre cómo Ben Kanute concilia la vida familiar y el entrenamiento en Arizona, utilizando un spa de natación para optimizar la comodidad y mejorar el rendimiento.","breadcrumb":{"@id":"https://www.h2xswimspa.com/blog/ben-kanute-training/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https://www.h2xswimspa.com/blog/ben-kanute-training/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https://www.h2xswimspa.com/blog/ben-kanute-training/#primaryimage","url":"https://h2xswimspa.es/blog/wp-content/uploads/2023/12/ben-kanute-hero.jpg","contentUrl":"https://www.h2xswimspa.com/blog/wp-content/uploads/2023/12/ben-kanute-hero.jpg","width":1200,"height":630,"caption":"triathlete ben kanute"},{"@type":"BreadcrumbList","@id":"https://www.h2xswimspa.com/blog/ben-kanute-training/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https://www.h2xswimspa.com/blog/"},{"@type":"ListItem","position":2,"name":"Catching up with pro triathlete Ben Kanute"}]},{"@type":"WebSite","@id":"https://www.h2xswimspa.com/blog/#website","url":"https://h2xswimspa.es/blog/","name":"H2X Swim Spas Blog","description":"Consejos, trucos e inspiración para spas de natación","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https://www.h2xswimspa.com/blog/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https://www.h2xswimspa.com/blog/#/schema/person/dc1771e0c9fb19465b7fe44f3ab49707","name":"Chris","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https://www.h2xswimspa.com/blog/#/schema/person/image/","url":"https://secure.gravatar.com/avatar/a6673e0ebf2d20b095fba3eedab24827a79602f497cda2cc76d0e12fff76ceb7?s=96&d=mm&r=g","contentUrl":"https://secure.gravatar.com/avatar/a6673e0ebf2d20b095fba3eedab24827a79602f497cda2cc76d0e12fff76ceb7?s=96&d=mm&r=g","caption":"Chris"},"sameAs":["http://Master%20Spas%20Staff"]}]}},"_links":{"self":[{"href":"https://www.h2xswimspa.com/blog/wp-json/wp/v2/posts/194","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https://www.h2xswimspa.com/blog/wp-json/wp/v2/posts"}],"about":[{"href":"https://www.h2xswimspa.com/blog/wp-json/wp/v2/types/post"}],"author":[{"embeddable":true,"href":"https://www.h2xswimspa.com/blog/wp-json/wp/v2/users/3"}],"replies":[{"embeddable":true,"href":"https://www.h2xswimspa.com/blog/wp-json/wp/v2/comments?post=194"}],"version-history":[{"count":4,"href":"https://www.h2xswimspa.com/blog/wp-json/wp/v2/posts/194/revisions"}],"predecessor-version":[{"id":347,"href":"https://www.h2xswimspa.com/blog/wp-json/wp/v2/posts/194/revisions/347"}],"wp:featuredmedia":[{"embeddable":true,"href":"https://www.h2xswimspa.com/blog/wp-json/wp/v2/media/346"}],"wp:attachment":[{"href":"https://www.h2xswimspa.com/blog/wp-json/wp/v2/media?parent=194"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https://www.h2xswimspa.com/blog/wp-json/wp/v2/categories?post=194"},{"taxonomy":"post_tag","embeddable":true,"href":"https://www.h2xswimspa.com/blog/wp-json/wp/v2/tags?post=194"}],"curies":[{"name":"wp","href":"https://api.w.org/{rel}","templated":true}]}}